{"id":8350,"date":"2024-06-17T11:25:16","date_gmt":"2024-06-17T14:25:16","guid":{"rendered":"https:\/\/www.univ-guyane.fr\/?p=8350"},"modified":"2024-06-17T11:34:00","modified_gmt":"2024-06-17T14:34:00","slug":"ouverture-de-14-sujets-de-these-a-luniversite-de-guyane","status":"publish","type":"post","link":"https:\/\/www.univ-guyane.fr\/es\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/","title":{"rendered":"Apertura de 14 temas de tesis en la Universidad de Guyana"},"content":{"rendered":"<div id=\"fws_6a0493bfc63cc\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  chapo\" >\n\t<h2>La Universidad de Guyana se complace en anunciar la apertura de 14 asignaturas de tesis, abiertas a candidatos franceses y extranjeros que deseen proseguir su investigaci\u00f3n doctoral en nuestra instituci\u00f3n.<\/h2>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p><span class=\"nectar-dropcap\" >C <\/span>as oportunidades abarcan una amplia gama de campos acad\u00e9micos, proporcionando un entorno estimulante e innovador a los futuros investigadores. Al final del periodo de selecci\u00f3n, s\u00f3lo los 7 mejores candidatos obtendr\u00e1n un contrato de doctorado. Por lo tanto, invitamos a todos los candidatos apasionados y con talento a que presenten su solicitud y se unan a nuestra comunidad acad\u00e9mica din\u00e1mica y diversa. <a href=\"https:\/\/www.univ-guyane.fr\/es\/ugfm\/?dir=docs\/dirved\/ecole-doctorale\/sujets-de-these\/2024-2025\" target=\"_blank\" rel=\"noopener\">Informaci\u00f3n<\/a>.<\/p>\n<p><strong>Tema 1:<\/strong> UMR EcoFog _ T\u00edtulo: Modelizaci\u00f3n matem\u00e1tica y aplicaci\u00f3n en la gesti\u00f3n forestal: control \u00f3ptimo, viabilidad y datos ausentes. Equipo de direcci\u00f3n del proyecto: Sr. Abdennebi OMRANE, Profesor universitario (director de tesis), Sr. Joan SALDANA, Profesor universitario (co-supervisor), Sr. Lo\u00efc LOUISON, Profesor titular (co-supervisor).<\/p>\n<p><strong>Tema 2:<\/strong> UMR EcoFog _ T\u00edtulo: Sensibilidad hidr\u00e1ulica y t\u00e9rmica del bosque guyan\u00e9s en el contexto del cambio global. Equipo de direcci\u00f3n del proyecto: Sr. Cl\u00e9ment STAHL, CRCN-HDR (director de tesis), Sra. Sabrina COSTE, Ma\u00eetre de conf\u00e9rence, titulaire d'une ADT (codirectora), Sr. Niklas TYSKLIND, CRCN (codirector).<\/p>\n<p><strong>Tema 3:<\/strong> UMR EcoFog _ T\u00edtulo: Ecolog\u00eda y conservaci\u00f3n del Jaguar en la Guayana Francesa en un contexto de conflicto con el hombre y la fauna dom\u00e9stica: un enfoque gen\u00e9tico no invasivo. Equipo de direcci\u00f3n del proyecto: Sr. Erwan QU\u00c9M\u00c9R\u00c9, Chercheur-HDR, (Director de tesis), Sr. Niklas TYSKLIND, CRCN (Co-supervisor), Sra. St\u00e9phanie BARTHE, Jefa de la Unidad de Conocimientos T\u00e9cnicos de Guyana (Co-supervisora).<\/p>\n<p><strong>Tema 4:<\/strong> UMR EcoFog _ T\u00edtulo: Estudio del impacto de la ecolog\u00eda tr\u00f3fica sobre la composici\u00f3n y la actividad del veneno de las hormigas de la Guayana Francesa. Equipo de direcci\u00f3n del proyecto: M. J\u00e9r\u00f4me ORIVEL, Directeur de recherche-HDR (director de tesis), M. Axel TOUCHARD, Docteur (co-supervisor).<\/p>\n<p><strong>Tema 5:<\/strong> UMR Espace-Dev- T\u00edtulo: Convertidores multinivel para arquitecturas \u00f3ptimas de sistemas estacionarios de energ\u00edas renovables en zonas tropicales y aisladas. Equipo de direcci\u00f3n del proyecto: M. Antoine PRIMEROSE, Professeur des universit\u00e9s, (director de tesis), M. Chabakata MAHAMAT, Ma\u00eetre de conf\u00e9rences (co-supervisor).<\/p>\n<p><strong>Tema 6:<\/strong> UMR Espace-Dev- T\u00edtulo: Estudio de las islas urbanas de calor (UHI) en la meseta de Guayana mediante teledetecci\u00f3n espacial. Equipo de direcci\u00f3n del proyecto: Sr. Antoine Primerose, Profesor universitario (director de tesis), Sra. Jessica Bechet, Profesora titular (codirectora).<\/p>\n<p><strong>Tema 7:<\/strong> IPG - T\u00edtulo: Identificaci\u00f3n de candidatos a biopesticidas entre las bacterias asociadas al mosquito Aedes aegypti. Equipo de direcci\u00f3n del proyecto: Mme Mathilde GENDRIN, Charg\u00e9e de recherches- HDR, (Directora de tesis)<\/p>\n<p><strong>Tema 8:<\/strong> IPG - T\u00edtulo: Herramientas innovadoras de vigilancia epidemiol\u00f3gica a partir de aguas residuales: aplicaci\u00f3n a las enfermedades emergentes amaz\u00f3nicas y a los agentes pat\u00f3genos de inter\u00e9s prioritario en la Guayana Francesa. Equipo de direcci\u00f3n del proyecto: Mme Dominique ROUSSET, HDR (directora de tesis), Olivier ROHR, HDR (codirector)<\/p>\n<p><strong>Tema 9:<\/strong> UAR LEEISA - T\u00edtulo: Jaguares y criadores en la Guayana Francesa: \u00bfrelaciones que cambian con la evoluci\u00f3n de los socio-ecosistemas pastorales costeros? Equipo de direcci\u00f3n del proyecto: M. Guillaume ODONNE, Charg\u00e9 de recherche-HDR (PhD supervisor), Marianne PALISSE, Ma\u00eetre de conf\u00e9rences (Co-supervisor)<\/p>\n<p><strong>Tema 10:<\/strong> UAR LEEISA - T\u00edtulo: Morfodin\u00e1mica de una playa arenosa estuarina bajo el forzamiento de un banco de lodo: el caso de la playa de Awala-Yalimapo. Equipo de direcci\u00f3n del proyecto: M. Antoine GARDEL, Charg\u00e9 de recherche-HDR, (Director de tesis), M. Guillaume BRUNIER, PhD (Co-supervisor)<\/p>\n<p><strong>Tema 11:<\/strong> UR MINEA - T\u00edtulo: \"L'espace amazonien, enjeux de pouvoir, de savoirs et de m\u00e9moires\". Equipo de direcci\u00f3n del proyecto: Sr. Jean MOOMOU, Profesor universitario (director de tesis), Sra. Myl\u00e8ne DANGLADES, Profesora titular (codirectora), Sra. Natali Fabiana DA COSTA E SILVA, Profesora titular (codirectora).<\/p>\n<p><strong>Sujeto 12:<\/strong> UR MINEA - T\u00edtulo: Agua, problemas, poderes y creencias en Amazonia. Equipo de direcci\u00f3n del proyecto: Sra. Monique BLERALD, Profesora universitaria (directora de tesis), Sra. Myl\u00e8ne DANGLADES, Profesora titular (codirectora), Sra. Audrey DEBIBAKAS, Profesora titular (codirectora).<\/p>\n<p><strong>Tema 13:<\/strong> UMR QualiSud - T\u00edtulo: Impacto de la maduraci\u00f3n en las composiciones de l\u00edpidos y polisac\u00e1ridos de la pulpa de moucaya (Acrocomia aculeata). Optimizaci\u00f3n de los procesos de nanoformulaci\u00f3n. Equipo de direcci\u00f3n del proyecto: Didier BEREAU, Profesor universitario (director de tesis), Thierry BENVEGNU, Profesor universitario (codirector), Jean-Charles ROBINSON, Profesor universitario (codirector de tesis), Elodie JEAN-MARIE, Profesora titular (codirectora).<\/p>\n<p><strong>Tema 14:<\/strong> TBIP- T\u00edtulo: Estudio de pat\u00f3genos veterinarios de riesgo zoon\u00f3tico y\/o de importancia econ\u00f3mica en el medio amaz\u00f3nico. Equipo de direcci\u00f3n del proyecto: Sra. Ghislaine PREVOT, Profesora universitaria (directora de tesis), Sra. Marine GINOUVES, Doctora (co-supervisora).<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"La Universidad de Guyana se complace en anunciar la apertura de 14 asignaturas de tesis, disponibles para los candidatos...","protected":false},"author":1,"featured_media":8361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":573,"footnotes":""},"categories":[183],"tags":[186,228],"class_list":{"0":"post-8350","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ed","8":"tag-ecole-doctorale","9":"tag-these"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ouverture de 14 sujets de th\u00e8se \u00e0 l&#039;Universit\u00e9 de Guyane &#8212; Universit\u00e9 de Guyane<\/title>\n<meta name=\"description\" content=\"Postulez d\u00e8s maintenant pour l&#039;une des 14 opportunit\u00e9s de th\u00e8se passionnantes dans divers domaines acad\u00e9miques. Rejoignez l&#039;\u00e9cole doctorale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.univ-guyane.fr\/es\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ouverture de 14 sujets de th\u00e8se \u00e0 l&#039;Universit\u00e9 de Guyane &#8212; Universit\u00e9 de Guyane\" \/>\n<meta property=\"og:description\" content=\"Postulez d\u00e8s maintenant pour l&#039;une des 14 opportunit\u00e9s de th\u00e8se passionnantes dans divers domaines acad\u00e9miques. Rejoignez l&#039;\u00e9cole doctorale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.univ-guyane.fr\/es\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/\" \/>\n<meta property=\"og:site_name\" content=\"Universit\u00e9 de Guyane\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univguyane\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T14:25:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T14:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/ecole-doctorale-univ-guyane.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1013\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Loiti\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@univguyane\" \/>\n<meta name=\"twitter:site\" content=\"@univguyane\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Loiti\u00e8re\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/\"},\"author\":{\"name\":\"Erick Loiti\u00e8re\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\"},\"headline\":\"Ouverture de 14 sujets de th\u00e8se \u00e0 l&rsquo;Universit\u00e9 de Guyane\",\"datePublished\":\"2024-06-17T14:25:16+00:00\",\"dateModified\":\"2024-06-17T14:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/\"},\"wordCount\":986,\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/ecole-doctorale-univ-guyane.jpg\",\"keywords\":[\"\u00c9cole doctorale\",\"th\u00e8se\"],\"articleSection\":[\"\u2022 ED\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/\",\"name\":\"Ouverture de 14 sujets de th\u00e8se \u00e0 l'Universit\u00e9 de Guyane &#8212; Universit\u00e9 de Guyane\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/ecole-doctorale-univ-guyane.jpg\",\"datePublished\":\"2024-06-17T14:25:16+00:00\",\"dateModified\":\"2024-06-17T14:34:00+00:00\",\"description\":\"Postulez d\u00e8s maintenant pour l'une des 14 opportunit\u00e9s de th\u00e8se passionnantes dans divers domaines acad\u00e9miques. Rejoignez l'\u00e9cole doctorale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/ecole-doctorale-univ-guyane.jpg\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/ecole-doctorale-univ-guyane.jpg\",\"width\":1800,\"height\":1013,\"caption\":\"Ecole doctorale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/06\\\/17\\\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ouverture de 14 sujets de th\u00e8se \u00e0 l&rsquo;Universit\u00e9 de Guyane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"name\":\"Universit\u00e9 de Guyane\",\"description\":\"Au c\u0153ur de l&#039;amazonie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"alternateName\":\"UG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.univ-guyane.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\",\"name\":\"Universit\u00e9 de Guyane\",\"alternateName\":\"UG\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"width\":1024,\"height\":1024,\"caption\":\"Universit\u00e9 de Guyane\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univguyane\",\"https:\\\/\\\/x.com\\\/univguyane\",\"https:\\\/\\\/gf.linkedin.com\\\/school\\\/universite-de-guyane\\\/\",\"https:\\\/\\\/www.instagram.com\\\/univ_guyane\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\",\"name\":\"Erick Loiti\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"caption\":\"Erick Loiti\u00e8re\"},\"sameAs\":[\"http:\\\/\\\/www.univ-guyane.fr\"],\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/es\\\/author\\\/eloitierdbz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apertura de 14 temas de tesis en la Universidad de Guyana - Universit\u00e9 de Guyane","description":"Solicite ahora una de las 14 interesantes oportunidades de doctorado en diversos campos acad\u00e9micos. \u00danete a la escuela de doctorado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.univ-guyane.fr\/es\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/","og_locale":"es_ES","og_type":"article","og_title":"Ouverture de 14 sujets de th\u00e8se \u00e0 l'Universit\u00e9 de Guyane &#8212; Universit\u00e9 de Guyane","og_description":"Postulez d\u00e8s maintenant pour l'une des 14 opportunit\u00e9s de th\u00e8se passionnantes dans divers domaines acad\u00e9miques. Rejoignez l'\u00e9cole doctorale.","og_url":"https:\/\/www.univ-guyane.fr\/es\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/","og_site_name":"Universit\u00e9 de Guyane","article_publisher":"https:\/\/www.facebook.com\/univguyane","article_published_time":"2024-06-17T14:25:16+00:00","article_modified_time":"2024-06-17T14:34:00+00:00","og_image":[{"width":1800,"height":1013,"url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/ecole-doctorale-univ-guyane.jpg","type":"image\/jpeg"}],"author":"Erick Loiti\u00e8re","twitter_card":"summary_large_image","twitter_creator":"@univguyane","twitter_site":"@univguyane","twitter_misc":{"Escrito por":"Erick Loiti\u00e8re","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/#article","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/"},"author":{"name":"Erick Loiti\u00e8re","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179"},"headline":"Ouverture de 14 sujets de th\u00e8se \u00e0 l&rsquo;Universit\u00e9 de Guyane","datePublished":"2024-06-17T14:25:16+00:00","dateModified":"2024-06-17T14:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/"},"wordCount":986,"publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/ecole-doctorale-univ-guyane.jpg","keywords":["\u00c9cole doctorale","th\u00e8se"],"articleSection":["\u2022 ED"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/","url":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/","name":"Apertura de 14 temas de tesis en la Universidad de Guyana - Universit\u00e9 de Guyane","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/#primaryimage"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/ecole-doctorale-univ-guyane.jpg","datePublished":"2024-06-17T14:25:16+00:00","dateModified":"2024-06-17T14:34:00+00:00","description":"Solicite ahora una de las 14 interesantes oportunidades de doctorado en diversos campos acad\u00e9micos. \u00danete a la escuela de doctorado.","breadcrumb":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/#primaryimage","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/ecole-doctorale-univ-guyane.jpg","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/ecole-doctorale-univ-guyane.jpg","width":1800,"height":1013,"caption":"Ecole doctorale"},{"@type":"BreadcrumbList","@id":"https:\/\/www.univ-guyane.fr\/2024\/06\/17\/ouverture-de-14-sujets-de-these-a-luniversite-de-guyane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.univ-guyane.fr\/"},{"@type":"ListItem","position":2,"name":"Ouverture de 14 sujets de th\u00e8se \u00e0 l&rsquo;Universit\u00e9 de Guyane"}]},{"@type":"WebSite","@id":"https:\/\/www.univ-guyane.fr\/#website","url":"https:\/\/www.univ-guyane.fr\/","name":"Universidad de Guyana","description":"En el coraz\u00f3n de la Amazonia","publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"alternateName":"UG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.univ-guyane.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.univ-guyane.fr\/#organization","name":"Universidad de Guyana","alternateName":"UG","url":"https:\/\/www.univ-guyane.fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","width":1024,"height":1024,"caption":"Universit\u00e9 de Guyane"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univguyane","https:\/\/x.com\/univguyane","https:\/\/gf.linkedin.com\/school\/universite-de-guyane\/","https:\/\/www.instagram.com\/univ_guyane\/"]},{"@type":"Person","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179","name":"Erick Loiti\u00e8re","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","caption":"Erick Loiti\u00e8re"},"sameAs":["http:\/\/www.univ-guyane.fr"],"url":"https:\/\/www.univ-guyane.fr\/es\/author\/eloitierdbz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts\/8350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/comments?post=8350"}],"version-history":[{"count":3,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts\/8350\/revisions"}],"predecessor-version":[{"id":8359,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts\/8350\/revisions\/8359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/media\/8361"}],"wp:attachment":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/media?parent=8350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/categories?post=8350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/tags?post=8350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}