{"id":8993,"date":"2018-06-16T10:33:26","date_gmt":"2018-06-16T13:33:26","guid":{"rendered":"https:\/\/www.univ-guyane.fr\/?p=8993"},"modified":"2024-07-15T11:22:42","modified_gmt":"2024-07-15T14:22:42","slug":"thierry-a-la-decouverte-du-rallye-des-savanes","status":"publish","type":"post","link":"https:\/\/www.univ-guyane.fr\/es\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/","title":{"rendered":"Thierry - Descubriendo el Rallye des Savanes"},"content":{"rendered":"<div id=\"fws_6a03d8ed30daf\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  chapo\" >\n\t<h2>Conocemos a Thierry, un apasionado de los rallies extraordinarios. Nos cuenta c\u00f3mo descubri\u00f3 el mundo de los rallys en la meseta de Guayana. Una pasi\u00f3n que requiere algo m\u00e1s que habilidades al volante.<\/h2>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<h3>H\u00e1blenos de usted.<\/h3>\n<p>Estoy destinado en el \u00c9SP\u00c9, donde me encargo de la inform\u00e1tica. Esencialmente, la funci\u00f3n de nuestro departamento es poner a disposici\u00f3n los dispositivos digitales necesarios para el buen funcionamiento de la ense\u00f1anza y la administraci\u00f3n dentro del componente, proponer otros nuevos y garantizar el buen funcionamiento de los ya existentes. Esta labor la comparto con mi colega Marc Miatti. Por mi parte, administro los servidores de \u00c9SP\u00c9 basados en Linux, incluidos el correo electr\u00f3nico, el servidor web, el almacenamiento en la nube y la red, tanto en el campus de Cayena como en Saint-Laurent, donde tenemos una sucursal. Tambi\u00e9n desarrollo diversas aplicaciones para cubrir necesidades en t\u00e9rminos de cuadros de mando, producci\u00f3n autom\u00e1tica de documentos (listas de asistencia, por ejemplo) o gesti\u00f3n m\u00e1s t\u00e9cnica. De forma m\u00e1s transversal, gestiono los aspectos t\u00e9cnicos de la plataforma de ense\u00f1anza de la universidad, que es una evoluci\u00f3n de la que exist\u00eda en la \u00c9SP\u00c9 antes de la creaci\u00f3n de la UG.<\/p>\n<h3>\u00bfPor qu\u00e9 eligi\u00f3 el rally? \u00bfCu\u00e1ndo desarroll\u00f3 esta pasi\u00f3n?<\/h3>\n<p>Cuando llegu\u00e9 a la Guayana Francesa, enseguida me di cuenta de que mi fiel 205 no pod\u00eda llevarme a todas partes: algunas pistas me resultaban inaccesibles. As\u00ed que opt\u00e9 r\u00e1pidamente por un Land Rover 4\u00d74, famoso por su robustez y su capacidad de traves\u00eda. Con nuestra asociaci\u00f3n Cayenne Land, atravesamos las pistas de la Guayana Francesa, pero tambi\u00e9n de Brasil y Surinam; sab\u00edamos que all\u00ed se celebraba regularmente una modalidad de rally, pero era dif\u00edcil obtener informaci\u00f3n. En 2012, conocimos a 2 tripulaciones de la Guayana Francesa que participaban en el \"Rallye des Savanes\" y as\u00ed empez\u00f3 todo: con uno de mis amigos de la asociaci\u00f3n Cayenne Land, Jean-No\u00ebl CANOVA, nos inscribimos, \u00e9l como piloto y yo como navegante.<\/p>\n<h3>\u00bfC\u00f3mo fueron tus primeros rallies? \u00bfTiene buenos recuerdos?<\/h3>\n<p>Fue un comienzo dif\u00edcil: nuestros compa\u00f1eros, que ya ten\u00edan un poco de experiencia, nos explicaron el funcionamiento de las pruebas, pero cuando salimos por primera vez (se celebra por la noche, hacia las 21.00 horas) nos dieron las instrucciones... \u00a1en neerland\u00e9s! Afortunadamente, fue un error que se corrigi\u00f3 m\u00e1s tarde esa misma noche (el rally siempre empieza de noche y las instrucciones se traducen al ingl\u00e9s para los internacionales). Al principio, intentamos centrarnos en la orientaci\u00f3n en s\u00ed (cada ronda consta de varias etapas basadas en instrucciones estandarizadas) y de alguna manera conseguimos llegar a los puntos de llegada, \u00a1pero no a tiempo! \u00c9sa es la dificultad del Rallye des Savanes: no s\u00f3lo se trata de una carrera de orientaci\u00f3n (hay que conseguir seguir la ruta trazada por los organizadores), sino que tambi\u00e9n hay que ser constante, porque hay que respetar el horario lo m\u00e1s fielmente posible. No es un rally de velocidad: ir demasiado r\u00e1pido te hace perder puntos, pero tambi\u00e9n ir demasiado despacio... Por otro lado, pasamos la mayor parte del tiempo en pistas, o incluso completamente fuera de pista cuando estamos en las famosas sabanas que dan nombre al rally.<\/p>\n<h3>\u00bfEn cu\u00e1ntos rallies ha participado? \u00bfCu\u00e1l fue su favorito o el que m\u00e1s impresi\u00f3n le caus\u00f3?<\/h3>\n<p>Ya hemos participado en 7 ediciones del Rallye des Savanes, adem\u00e1s de un Eco Challenge, que es una versi\u00f3n \"light\" que se celebra en otra \u00e9poca del a\u00f1o. Competimos en la categor\u00eda \"internacional\", que incluye a todas las tripulaciones no surinamesas, principalmente de la Guayana Francesa (ahora suele haber entre 6 y 7 veh\u00edculos guyaneses en la salida), Trinidad, los Pa\u00edses Bajos y, a veces, Brasil u otros pa\u00edses. Durante las 3 primeras ediciones, adquirimos experiencia sobre el funcionamiento de las pruebas y del rally en s\u00ed, lo que nos permiti\u00f3 ganar en nuestra categor\u00eda (internacional) en 2015, 2016 y 2017. Por supuesto, no faltan los buenos recuerdos, ya que a menudo nos encontramos con los mismos competidores (de Guyana o de otros lugares) de un a\u00f1o para otro. La organizaci\u00f3n del rally es excepcional y atravesamos algunos sectores magn\u00edficos, as\u00ed que s\u00ed, hay buenos recuerdos. Me gusta especialmente el amanecer despu\u00e9s de haber conducido toda la noche tras la salida: en general, no tienes ni idea de d\u00f3nde est\u00e1s (vas de un punto a otro) y el paisaje se te va revelando poco a poco. Tambi\u00e9n recuerdo las noches pasadas en los campings del bosque, y los despertares a veces bruscos. En 2012, a las 5 de la ma\u00f1ana de un domingo, los organizadores hicieron sonar petardos (un cl\u00e1sico entre nuestros amigos surinameses) e hicieron pasar por el campamento a toda una banda de m\u00fasica, tocando a pleno pulm\u00f3n. Ni que decir tiene que ese d\u00eda no son\u00f3 el despertador. Las sabanas de arena blanca son bastante diferentes de lo que se encuentra en la mayor parte de la Guayana Francesa (hay un poco en los alrededores de Sinnamary o Mana): la vegetaci\u00f3n es escasa, se puede ver bastante lejos, es arenosa, pero las pruebas que generalmente se realizan all\u00ed (orientaci\u00f3n en im\u00e1genes a\u00e9reas) son nuestro punto d\u00e9bil, as\u00ed que el recuerdo es mixto...<\/p>\n<h3>\u00bfHay alg\u00fan rally que te gustar\u00eda hacer?<\/h3>\n<p>Por supuesto. Hay otras pruebas que me tentar\u00edan, pero el Rallye des Savanes es una combinaci\u00f3n \u00fanica de orientaci\u00f3n y regularidad que no conozco en ning\u00fan otro lugar del mundo. No muy lejos de nosotros, en Guyana, se celebra cada a\u00f1o el Pakaraima Mountain Safari, que parece m\u00e1s un raid que una competici\u00f3n, pero que permitir\u00eda conocer mejor este pa\u00eds cercano. M\u00e1s lejos, en Polonia y Alemania, tiene lugar el Breslau, un rally de traves\u00eda m\u00e1s t\u00e9cnico, pero que no est\u00e1 en la misma categor\u00eda...<\/p>\n<h3>\u00bfPuede hablarnos de un mitin t\u00edpico?<\/h3>\n<p>El Rallye des Savanes es una de las pruebas del campeonato de rallyes de Surinam. Siempre se celebra en torno al D\u00eda de Todos los Santos. El primer veh\u00edculo sale de Paramaribo hacia las 20.00 horas, seguido de un veh\u00edculo cada minuto. Suelen participar entre 60 y 90 veh\u00edculos de todas las categor\u00edas. Cada veh\u00edculo tiene al menos un conductor y un navegante. Pero en la categor\u00eda \"turista\" es posible llevar pasajeros. La salida se da el viernes por la tarde, y las pruebas se desarrollan durante toda la noche y el s\u00e1bado hasta \u00faltima hora de la tarde. En ese momento, descansamos en un lugar que no solemos conocer de antemano, normalmente en una hamaca. El domingo por la ma\u00f1ana, no nos despertamos demasiado tarde, porque el primer grupo sale a las 7 de la ma\u00f1ana... \u00a1a buscar el desayuno! S\u00ed, suele haber una prueba para encontrar el tentempi\u00e9 de la ma\u00f1ana, y es cuesti\u00f3n de no perd\u00e9rselo... Luego se suceden las pruebas hasta la noche. En el pasado, el rally terminaba el lunes por la noche (por lo que hab\u00eda un d\u00eda m\u00e1s), pero debido a la crisis econ\u00f3mica de Surinam, se redujo un d\u00eda. La ceremonia de entrega de premios suele celebrarse el martes o el mi\u00e9rcoles, pero para entonces ya estamos de vuelta en Cayena, \u00a1as\u00ed que nunca podemos asistir!<\/p>\n<h3>\u00bfQu\u00e9 tipo de preparaci\u00f3n requiere una aventura as\u00ed?<\/h3>\n<p>Ahora ya le hemos cogido el truco y solemos salir sin demasiados preparativos... Donde m\u00e1s trabajo hay que hacer es en la preparaci\u00f3n del veh\u00edculo: por supuesto, tiene que ser lo m\u00e1s fiable posible, los neum\u00e1ticos tienen que estar en buen estado y, preferiblemente, el cabrestante tiene que funcionar (nunca se est\u00e1 a salvo de dar un paso en falso o de sacar a otro competidor). En cuanto al equipamiento espec\u00edfico, el veh\u00edculo debe estar equipado con un cuentakil\u00f3metros (un contador de distancias con una precisi\u00f3n de 10 m para el modelo que tenemos), un GPS y una tableta capaz de conectarse a la red m\u00f3vil para poder utilizar diversas aplicaciones, en particular las fotos por sat\u00e9lite de Google Maps, muy \u00fatiles en determinadas circunstancias (en las famosas sabanas, por ejemplo).<\/p>\n<h3>\u00bfQu\u00e9 cualidades crees que necesitas para disfrutar de esta afici\u00f3n?<\/h3>\n<p>En primer lugar, es un deporte de equipo, as\u00ed que lo mejor es conocer bien a tu compa\u00f1ero, para facilitar las cosas. Para ser piloto, obviamente hay que tener conocimientos de conducci\u00f3n todoterreno, saber desenvolverse en terrenos fuera de la carretera o estar familiarizado con el 4\u00d74 en general. Las habilidades mec\u00e1nicas son bienvenidas porque, como en todos los deportes de este tipo, es preferible conocer bien tu veh\u00edculo y ser capaz de diagnosticar y reparar cualquier problema: a veces te pierdes y puedes encontrarte en dificultades en medio de la nada. En cuanto a la navegaci\u00f3n, hay varias categor\u00edas de pruebas, cada una de las cuales requiere habilidades diferentes:<\/p>\n<ul class=\"ug-list pine-list\">\n<li>Las pruebas en las que hay que seguir una serie de instrucciones exigen rigor y vigilancia;<\/li>\n<li>Pruebas en las que hay que calcular la mejor ruta en un mapa dado: evaluar las distancias y saber orientarse en el espacio;<\/li>\n<li>Pruebas de orientaci\u00f3n con fotos a\u00e9reas: buenas dotes de observaci\u00f3n, capacidad para emparejar fragmentos de im\u00e1genes tomadas desde distintos \u00e1ngulos y a diferentes escalas;<\/li>\n<li>En todos los actos: \u00a1preg\u00fantese qu\u00e9 trampa nos han tendido los organizadores!<\/li>\n<\/ul>\n<p>Enlaces : <a href=\"http:\/\/cayenneland.org\/\" target=\"_blank\" rel=\"noopener\">Tierra de Cayenas<\/a> |\u00a0<a href=\"http:\/\/sarkonline.com\/\" target=\"_blank\" rel=\"noopener\">SARK (Surinaamse Auto Rally Klub)<\/a><\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Conocemos a Thierry, un apasionado de los rallyes extraordinarios. Nos cuenta c\u00f3mo...","protected":false},"author":1,"featured_media":8995,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":11,"footnotes":""},"categories":[196],"tags":[197],"class_list":{"0":"post-8993","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-portraits","8":"tag-portraits"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes &#8212; Universit\u00e9 de Guyane<\/title>\n<meta name=\"description\" content=\"Partez \u00e0 la d\u00e9couverte du Rallye des Savanes en compagnie de Thierry et plongez dans une exp\u00e9rience unique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.univ-guyane.fr\/es\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes &#8212; Universit\u00e9 de Guyane\" \/>\n<meta property=\"og:description\" content=\"Partez \u00e0 la d\u00e9couverte du Rallye des Savanes en compagnie de Thierry et plongez dans une exp\u00e9rience unique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.univ-guyane.fr\/es\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/\" \/>\n<meta property=\"og:site_name\" content=\"Universit\u00e9 de Guyane\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univguyane\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-16T13:33:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-15T14:22:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Loiti\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@univguyane\" \/>\n<meta name=\"twitter:site\" content=\"@univguyane\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Loiti\u00e8re\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/\"},\"author\":{\"name\":\"Erick Loiti\u00e8re\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\"},\"headline\":\"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes\",\"datePublished\":\"2018-06-16T13:33:26+00:00\",\"dateModified\":\"2024-07-15T14:22:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/\"},\"wordCount\":2005,\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg\",\"keywords\":[\"Portraits\"],\"articleSection\":[\"\u2022\u00a0Portraits\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/\",\"name\":\"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes &#8212; Universit\u00e9 de Guyane\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg\",\"datePublished\":\"2018-06-16T13:33:26+00:00\",\"dateModified\":\"2024-07-15T14:22:42+00:00\",\"description\":\"Partez \u00e0 la d\u00e9couverte du Rallye des Savanes en compagnie de Thierry et plongez dans une exp\u00e9rience unique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg\",\"width\":1200,\"height\":800,\"caption\":\"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/06\\\/16\\\/thierry-a-la-decouverte-du-rallye-des-savanes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"name\":\"Universit\u00e9 de Guyane\",\"description\":\"Au c\u0153ur de l&#039;amazonie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"alternateName\":\"UG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.univ-guyane.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\",\"name\":\"Universit\u00e9 de Guyane\",\"alternateName\":\"UG\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"width\":1024,\"height\":1024,\"caption\":\"Universit\u00e9 de Guyane\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univguyane\",\"https:\\\/\\\/x.com\\\/univguyane\",\"https:\\\/\\\/gf.linkedin.com\\\/school\\\/universite-de-guyane\\\/\",\"https:\\\/\\\/www.instagram.com\\\/univ_guyane\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\",\"name\":\"Erick Loiti\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"caption\":\"Erick Loiti\u00e8re\"},\"sameAs\":[\"http:\\\/\\\/www.univ-guyane.fr\"],\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/es\\\/author\\\/eloitierdbz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes &#8212; Universit\u00e9 de Guyane","description":"Partez \u00e0 la d\u00e9couverte du Rallye des Savanes en compagnie de Thierry et plongez dans une exp\u00e9rience unique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.univ-guyane.fr\/es\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/","og_locale":"es_ES","og_type":"article","og_title":"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes &#8212; Universit\u00e9 de Guyane","og_description":"Partez \u00e0 la d\u00e9couverte du Rallye des Savanes en compagnie de Thierry et plongez dans une exp\u00e9rience unique.","og_url":"https:\/\/www.univ-guyane.fr\/es\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/","og_site_name":"Universit\u00e9 de Guyane","article_publisher":"https:\/\/www.facebook.com\/univguyane","article_published_time":"2018-06-16T13:33:26+00:00","article_modified_time":"2024-07-15T14:22:42+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg","type":"image\/jpeg"}],"author":"Erick Loiti\u00e8re","twitter_card":"summary_large_image","twitter_creator":"@univguyane","twitter_site":"@univguyane","twitter_misc":{"Escrito por":"Erick Loiti\u00e8re","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/#article","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/"},"author":{"name":"Erick Loiti\u00e8re","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179"},"headline":"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes","datePublished":"2018-06-16T13:33:26+00:00","dateModified":"2024-07-15T14:22:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/"},"wordCount":2005,"publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg","keywords":["Portraits"],"articleSection":["\u2022\u00a0Portraits"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/","url":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/","name":"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes &#8212; Universit\u00e9 de Guyane","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/#primaryimage"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg","datePublished":"2018-06-16T13:33:26+00:00","dateModified":"2024-07-15T14:22:42+00:00","description":"Partez \u00e0 la d\u00e9couverte du Rallye des Savanes en compagnie de Thierry et plongez dans une exp\u00e9rience unique.","breadcrumb":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/#primaryimage","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-une-thierry-launay-rallye-de-savanes-universite-de-guyane_2.jpeg","width":1200,"height":800,"caption":"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.univ-guyane.fr\/2018\/06\/16\/thierry-a-la-decouverte-du-rallye-des-savanes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.univ-guyane.fr\/"},{"@type":"ListItem","position":2,"name":"Thierry \u2013 \u00e0 la d\u00e9couverte du Rallye des Savanes"}]},{"@type":"WebSite","@id":"https:\/\/www.univ-guyane.fr\/#website","url":"https:\/\/www.univ-guyane.fr\/","name":"Universidad de Guyana","description":"En el coraz\u00f3n de la Amazonia","publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"alternateName":"UG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.univ-guyane.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.univ-guyane.fr\/#organization","name":"Universidad de Guyana","alternateName":"UG","url":"https:\/\/www.univ-guyane.fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","width":1024,"height":1024,"caption":"Universit\u00e9 de Guyane"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univguyane","https:\/\/x.com\/univguyane","https:\/\/gf.linkedin.com\/school\/universite-de-guyane\/","https:\/\/www.instagram.com\/univ_guyane\/"]},{"@type":"Person","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179","name":"Erick Loiti\u00e8re","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","caption":"Erick Loiti\u00e8re"},"sameAs":["http:\/\/www.univ-guyane.fr"],"url":"https:\/\/www.univ-guyane.fr\/es\/author\/eloitierdbz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts\/8993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/comments?post=8993"}],"version-history":[{"count":3,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts\/8993\/revisions"}],"predecessor-version":[{"id":10023,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts\/8993\/revisions\/10023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/media\/8995"}],"wp:attachment":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/media?parent=8993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/categories?post=8993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/tags?post=8993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}