{"id":8996,"date":"2018-05-17T10:37:10","date_gmt":"2018-05-17T13:37:10","guid":{"rendered":"https:\/\/www.univ-guyane.fr\/?p=8996"},"modified":"2024-07-15T11:28:26","modified_gmt":"2024-07-15T14:28:26","slug":"jeanne-claire-lalternance-est-une-chance","status":"publish","type":"post","link":"https:\/\/www.univ-guyane.fr\/es\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/","title":{"rendered":"Jeanne-Claire, la alternancia es una oportunidad"},"content":{"rendered":"<div id=\"fws_6a03d8f62448b\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  chapo\" >\n\t<h2>Este mes conocemos a Jeanne-Claire, estudiante de Formaci\u00f3n Profesional en Gesti\u00f3n de Organizaciones. Con un pie en la universidad y otro en el trabajo, nos habla de su a\u00f1o de estudios en alternancia.<\/h2>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<h3>Pres\u00e9ntate.<\/h3>\n<p>Me llamo Jeanne-Claire CAREME CALONNE. Termin\u00e9 mis estudios secundarios en el Externat Saint Joseph, donde obtuve el bachillerato econ\u00f3mico y social. Segu\u00ed estudiando en el IUT de Kourou, donde obtuve el DUT en T\u00e9cnicas de Marketing. Actualmente estoy terminando mi a\u00f1o de carrera profesional en Gesti\u00f3n de Organizaciones - Creaci\u00f3n de Empresas (todav\u00eda en el IUT de Kourou\/Universidad CFA). Hago esta formaci\u00f3n en alternancia en CHAMAZONE PROMO, una peque\u00f1a empresa de promoci\u00f3n inmobiliaria filial del holding CHAMAZONE GROUP.<\/p>\n<h3>\u00bfPor qu\u00e9 eligi\u00f3 hacer este a\u00f1o un curso en alternancia?<\/h3>\n<p>Eleg\u00ed este camino porque era la continuaci\u00f3n l\u00f3gica de mi formaci\u00f3n en el IUT de Kourou, pero tambi\u00e9n porque es un t\u00edtulo multidisciplinar. Obviamente estudiamos gesti\u00f3n, pero tambi\u00e9n recursos humanos, finanzas, contabilidad general y en profundidad, estrategia empresarial y derecho. Tambi\u00e9n tenemos asignaturas transversales como comunicaci\u00f3n corporativa, responsabilidad social corporativa y tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n. Nos forman para convertirnos en futuros ejecutivos y gestores de empresas en todos los sectores de actividad. En mi opini\u00f3n, es la titulaci\u00f3n m\u00e1s completa y la que mejor se adaptaba a m\u00ed. La otra ventaja de este grado es que es una formaci\u00f3n en alternancia. Por tanto, me permite seguir mis cursos al tiempo que adquiero experiencia profesional. El ritmo de esta titulaci\u00f3n es ideal porque estamos en la empresa cada dos semanas. Esto nos permite seguir los proyectos en su totalidad.  Hay mucho que aprender en el aula, pero el programa de pr\u00e1cticas nos permite aplicar los conceptos aprendidos y, sobre todo, ponerlos en pr\u00e1ctica y ver los \u00e9xitos y los fracasos. Es una verdadera oportunidad para nosotros, y creo que es esencial si quieres completar tu formaci\u00f3n.<\/p>\n<h3>\u00bfCu\u00e1les son sus tareas vinculadas al trabajo?<strong><br \/>\n<\/strong><\/h3>\n<p>Mis tareas en CHAMAZONE PROMO son variadas. Como asistente de direcci\u00f3n, trabajo con todos los oficios. Como CHAMAZONE PROMO es una empresa peque\u00f1a con menos de 11 empleados, somos muy vers\u00e1tiles. Es una verdadera ventaja para mi aprendizaje. Soy polivalente, pero mis principales tareas son el marketing y la comunicaci\u00f3n. Mi principal tarea es adaptar la oferta de la empresa a las necesidades del mercado, para que sea m\u00e1s eficaz y operativa frente a la competencia. Para ello, he puesto en marcha las herramientas necesarias para controlar las ventas y la actividad administrativa, que antes no exist\u00edan. Estoy ayudando a digitalizar Chamazone Promo. Por ejemplo, he trabajado en la creaci\u00f3n de un software de gesti\u00f3n de las relaciones con los clientes y una aplicaci\u00f3n de seguimiento del sitio para los clientes. Tambi\u00e9n he ayudado a redise\u00f1ar el sitio web y he creado minisitios web para las promociones inmobiliarias que se comercializan. Me encargo de la comunicaci\u00f3n en las redes sociales. En estos momentos, estoy preparando nuestra participaci\u00f3n en el Sal\u00f3n del H\u00e1bitat, que tendr\u00e1 lugar en junio. Tambi\u00e9n hago un poco de contabilidad (archivo y entrada de datos).<\/p>\n<h3>\u00bfEn qu\u00e9 le ha beneficiado este a\u00f1o de formaci\u00f3n en alternancia?<\/h3>\n<p>He ganado mucho este a\u00f1o. En primer lugar, en el plano profesional. Mis semanas sobre el terreno me permiten poner inmediatamente en pr\u00e1ctica lo que he aprendido en teor\u00eda y mis conocimientos en mi empresa de acogida. Estoy construyendo una red profesional gracias a los contactos que hago cuando estoy en Chamazone. Es una baza real en mi CV. A nivel personal, descubro el mundo de los negocios y desarrollo mi personalidad: tengo m\u00e1s confianza en m\u00ed misma y soy m\u00e1s aut\u00f3noma.<\/p>\n<h3>\u00bfEs dif\u00edcil hacer formaci\u00f3n en alternancia?<\/h3>\n<p>No, no es dif\u00edcil estudiar en alternancia. S\u00f3lo requiere buena organizaci\u00f3n y rigor. Estamos en la empresa aproximadamente cada dos semanas y durante las vacaciones escolares. As\u00ed que tenemos que encontrar un ritmo entre las clases, el trabajo en la empresa y nuestra vida personal. Es un ritmo al que hay que acostumbrarse, pero merece la pena.<\/p>\n<h3>\u00bfQu\u00e9 planes tiene para el futuro?<strong><br \/>\n<\/strong><\/h3>\n<p>Todav\u00eda no he decidido nada, pero sigo dudando entre continuar mis estudios en un m\u00e1ster en la Guayana Francesa, en la Francia continental o en el extranjero; o hacer un a\u00f1o sab\u00e1tico, es decir, trabajar, hacer labores humanitarias o viajar antes de seguir con mi plan de carrera.<\/p>\n<h3>\u00bfTiene alg\u00fan consejo para los estudiantes que se sientan tentados a estudiar en alternancia?<\/h3>\n<p>\u00a1An\u00edmate! Es una experiencia magn\u00edfica y gratificante que te abre los ojos al mundo profesional. Es una verdadera oportunidad para ser curioso, aprender y poner en pr\u00e1ctica las lecciones, de modo que salgas de ella tanto m\u00e1s maduro. \u00a1Les dir\u00eda que no dudaran en elegir un curso en alternancia!<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Este mes conocemos a Jeanne-Claire, estudiante de formaci\u00f3n profesional en Gesti\u00f3n y...","protected":false},"author":1,"featured_media":8997,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":42,"footnotes":""},"categories":[196],"tags":[197],"class_list":{"0":"post-8996","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-portraits","8":"tag-portraits"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jeanne-Claire, l\u2019alternance est une chance &#8212; Universit\u00e9 de Guyane<\/title>\n<meta name=\"description\" content=\"Je me pr\u00e9sente, Jeanne-Claire CAREME CALONNE, de mon parcours scolaire \u00e0 mes \u00e9tudes sup\u00e9rieures en alternance chez CHAMAZONE PROMO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.univ-guyane.fr\/es\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeanne-Claire, l\u2019alternance est une chance &#8212; Universit\u00e9 de Guyane\" \/>\n<meta property=\"og:description\" content=\"Je me pr\u00e9sente, Jeanne-Claire CAREME CALONNE, de mon parcours scolaire \u00e0 mes \u00e9tudes sup\u00e9rieures en alternance chez CHAMAZONE PROMO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.univ-guyane.fr\/es\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/\" \/>\n<meta property=\"og:site_name\" content=\"Universit\u00e9 de Guyane\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univguyane\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-17T13:37:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-15T14:28:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Loiti\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@univguyane\" \/>\n<meta name=\"twitter:site\" content=\"@univguyane\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Loiti\u00e8re\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/\"},\"author\":{\"name\":\"Erick Loiti\u00e8re\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\"},\"headline\":\"Jeanne-Claire, l\u2019alternance est une chance\",\"datePublished\":\"2018-05-17T13:37:10+00:00\",\"dateModified\":\"2024-07-15T14:28:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/\"},\"wordCount\":1100,\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg\",\"keywords\":[\"Portraits\"],\"articleSection\":[\"\u2022\u00a0Portraits\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/\",\"name\":\"Jeanne-Claire, l\u2019alternance est une chance &#8212; Universit\u00e9 de Guyane\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg\",\"datePublished\":\"2018-05-17T13:37:10+00:00\",\"dateModified\":\"2024-07-15T14:28:26+00:00\",\"description\":\"Je me pr\u00e9sente, Jeanne-Claire CAREME CALONNE, de mon parcours scolaire \u00e0 mes \u00e9tudes sup\u00e9rieures en alternance chez CHAMAZONE PROMO.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg\",\"width\":1200,\"height\":800,\"caption\":\"Jeanne-Claire, l\u2019alternance est une chance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2018\\\/05\\\/17\\\/jeanne-claire-lalternance-est-une-chance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jeanne-Claire, l\u2019alternance est une chance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"name\":\"Universit\u00e9 de Guyane\",\"description\":\"Au c\u0153ur de l&#039;amazonie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"alternateName\":\"UG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.univ-guyane.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\",\"name\":\"Universit\u00e9 de Guyane\",\"alternateName\":\"UG\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"width\":1024,\"height\":1024,\"caption\":\"Universit\u00e9 de Guyane\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univguyane\",\"https:\\\/\\\/x.com\\\/univguyane\",\"https:\\\/\\\/gf.linkedin.com\\\/school\\\/universite-de-guyane\\\/\",\"https:\\\/\\\/www.instagram.com\\\/univ_guyane\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\",\"name\":\"Erick Loiti\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"caption\":\"Erick Loiti\u00e8re\"},\"sameAs\":[\"http:\\\/\\\/www.univ-guyane.fr\"],\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/es\\\/author\\\/eloitierdbz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jeanne-Claire, l\u2019alternance est une chance &#8212; Universit\u00e9 de Guyane","description":"Je me pr\u00e9sente, Jeanne-Claire CAREME CALONNE, de mon parcours scolaire \u00e0 mes \u00e9tudes sup\u00e9rieures en alternance chez CHAMAZONE PROMO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.univ-guyane.fr\/es\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/","og_locale":"es_ES","og_type":"article","og_title":"Jeanne-Claire, l\u2019alternance est une chance &#8212; Universit\u00e9 de Guyane","og_description":"Je me pr\u00e9sente, Jeanne-Claire CAREME CALONNE, de mon parcours scolaire \u00e0 mes \u00e9tudes sup\u00e9rieures en alternance chez CHAMAZONE PROMO.","og_url":"https:\/\/www.univ-guyane.fr\/es\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/","og_site_name":"Universit\u00e9 de Guyane","article_publisher":"https:\/\/www.facebook.com\/univguyane","article_published_time":"2018-05-17T13:37:10+00:00","article_modified_time":"2024-07-15T14:28:26+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg","type":"image\/jpeg"}],"author":"Erick Loiti\u00e8re","twitter_card":"summary_large_image","twitter_creator":"@univguyane","twitter_site":"@univguyane","twitter_misc":{"Escrito por":"Erick Loiti\u00e8re","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/#article","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/"},"author":{"name":"Erick Loiti\u00e8re","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179"},"headline":"Jeanne-Claire, l\u2019alternance est une chance","datePublished":"2018-05-17T13:37:10+00:00","dateModified":"2024-07-15T14:28:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/"},"wordCount":1100,"publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg","keywords":["Portraits"],"articleSection":["\u2022\u00a0Portraits"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/","url":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/","name":"Jeanne-Claire, l\u2019alternance est une chance &#8212; Universit\u00e9 de Guyane","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/#primaryimage"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg","datePublished":"2018-05-17T13:37:10+00:00","dateModified":"2024-07-15T14:28:26+00:00","description":"Je me pr\u00e9sente, Jeanne-Claire CAREME CALONNE, de mon parcours scolaire \u00e0 mes \u00e9tudes sup\u00e9rieures en alternance chez CHAMAZONE PROMO.","breadcrumb":{"@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/#primaryimage","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/portrait-2018-jeanne-claire-careme-calonne-universite-de-guyane-1640.jpeg","width":1200,"height":800,"caption":"Jeanne-Claire, l\u2019alternance est une chance"},{"@type":"BreadcrumbList","@id":"https:\/\/www.univ-guyane.fr\/2018\/05\/17\/jeanne-claire-lalternance-est-une-chance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.univ-guyane.fr\/"},{"@type":"ListItem","position":2,"name":"Jeanne-Claire, l\u2019alternance est une chance"}]},{"@type":"WebSite","@id":"https:\/\/www.univ-guyane.fr\/#website","url":"https:\/\/www.univ-guyane.fr\/","name":"Universidad de Guyana","description":"En el coraz\u00f3n de la Amazonia","publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"alternateName":"UG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.univ-guyane.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.univ-guyane.fr\/#organization","name":"Universidad de Guyana","alternateName":"UG","url":"https:\/\/www.univ-guyane.fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","width":1024,"height":1024,"caption":"Universit\u00e9 de Guyane"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univguyane","https:\/\/x.com\/univguyane","https:\/\/gf.linkedin.com\/school\/universite-de-guyane\/","https:\/\/www.instagram.com\/univ_guyane\/"]},{"@type":"Person","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179","name":"Erick Loiti\u00e8re","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","caption":"Erick Loiti\u00e8re"},"sameAs":["http:\/\/www.univ-guyane.fr"],"url":"https:\/\/www.univ-guyane.fr\/es\/author\/eloitierdbz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts\/8996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/comments?post=8996"}],"version-history":[{"count":2,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts\/8996\/revisions"}],"predecessor-version":[{"id":10025,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/posts\/8996\/revisions\/10025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/media\/8997"}],"wp:attachment":[{"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/media?parent=8996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/categories?post=8996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/es\/wp-json\/wp\/v2\/tags?post=8996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}