{"id":8321,"date":"2024-01-26T10:14:24","date_gmt":"2024-01-26T13:14:24","guid":{"rendered":"https:\/\/www.univ-guyane.fr\/?p=8321"},"modified":"2024-06-17T10:19:30","modified_gmt":"2024-06-17T13:19:30","slug":"ouverture-de-la-licence-staps-a-la-rentree-2024","status":"publish","type":"post","link":"https:\/\/www.univ-guyane.fr\/pt\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/","title":{"rendered":"Abertura do curso STAPS no in\u00edcio do ano acad\u00eamico de 2024"},"content":{"rendered":"<div id=\"fws_6a03cdd4c44f1\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  chapo\" >\n\t<h2>A Universidade da Guiana acrescentar\u00e1 um novo curso \u00e0 sua gama de cursos a partir do in\u00edcio do ano acad\u00eamico de 2024: o curso STAPS (Sciences et Techniques des Activit\u00e9s Physiques et Sportives), com especializa\u00e7\u00e3o espec\u00edfica em \"Educa\u00e7\u00e3o e Motricidade\". Essa iniciativa atende \u00e0 crescente demanda no campo da educa\u00e7\u00e3o f\u00edsica e do esporte, oferecendo aos alunos um treinamento dedicado ao ensino de atividades f\u00edsicas, esportivas e expressivas em uma variedade de contextos educacionais.<\/h2>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<article id=\"post-16581\" class=\"post-16581 post type-post status-publish format-standard has-post-thumbnail category-news-formation\">\n<div class=\"inner-wrap\">\n<div class=\"post-content\" data-hide-featured-media=\"0\">\n<div class=\"content-inner\">\n<div id=\"fws_65d51c754e4e4\" class=\"wpb_row vc_row-fluid vc_row\" data-column-margin=\"default\" data-midnight=\"dark\">\n<div class=\"row_col_wrap_12 col span_12 dark left\">\n<div class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div id=\"lipsum\">\n<span class=\"nectar-dropcap\" >C <\/span>ste curso, desenvolvido em estreita colabora\u00e7\u00e3o com a Reitoria e a Collectivit\u00e9 Territoriale de Guyane, reflete o forte compromisso da Universidade com a educa\u00e7\u00e3o, a sa\u00fade p\u00fablica e o desenvolvimento local. Seu objetivo \u00e9 equipar os futuros graduados com as habilidades necess\u00e1rias para se destacarem nas profiss\u00f5es de treinamento, orienta\u00e7\u00e3o e prepara\u00e7\u00e3o f\u00edsica e mental.<\/p>\n<h3>Treinamento vers\u00e1til<\/h3>\n<p>O novo curso STAPS se destaca por sua orienta\u00e7\u00e3o multifuncional, preparando os alunos para carreiras imediatas e abrindo perspectivas para estudos avan\u00e7ados. Os formandos poder\u00e3o fazer um Mestrado em Ensino, Educa\u00e7\u00e3o e Treinamento (MEEF) ou um Mestrado em STAPS, ampliando consideravelmente seus horizontes profissionais.<\/p>\n<p>Gra\u00e7as ao apoio da Collectivit\u00e9 Territoriale de Guyane e da cidade de Cayenne, as instala\u00e7\u00f5es localizadas a menos de 1 km da Universit\u00e9 de Guyane ser\u00e3o disponibilizadas aos alunos de gradua\u00e7\u00e3o. Essa proximidade facilitar\u00e1 o acesso \u00e0s instala\u00e7\u00f5es necess\u00e1rias para seu treinamento.<\/p>\n<h3>Treinamento necess\u00e1rio para atender \u00e0s necessidades da regi\u00e3o<\/h3>\n<p>As previs\u00f5es iniciais antecipam um fluxo de cerca de quarenta alunos para o primeiro ano (L1) desse curso, devido \u00e0 crescente demanda por estudos do STAPS em geral. Para os anos seguintes, o n\u00famero de alunos \u00e9 estimado em 30 para a Licen\u00e7a 2 (L2) e 28 para a Licen\u00e7a 3 (L3).<\/p>\n<p>A cria\u00e7\u00e3o desse diploma STAPS tamb\u00e9m \u00e9 uma oportunidade significativa para os jovens da regi\u00e3o cursarem o ensino superior sem precisar viajar para Guadalupe (1.600 km) ou para a Fran\u00e7a (7.500 km). Entre 2018 e 2023, 252 alunos do \u00faltimo ano na Guiana Francesa escolheram essa rota, de acordo com dados do Parcours sup Guyane.<\/p>\n<p>O diploma STAPS fornecer\u00e1 habilidades essenciais para atender \u00e0s necessidades da Acad\u00e9mie em termos de ensino de educa\u00e7\u00e3o f\u00edsica e esporte (EPS). Atualmente, h\u00e1 quase 80 vagas para professores de educa\u00e7\u00e3o f\u00edsica na Acad\u00e9mie, o que est\u00e1 prejudicando o ensino dessa disciplina em coll\u00e8ges e lyc\u00e9es. O bacharelado oferece uma oportunidade de preencher essas lacunas por meio da forma\u00e7\u00e3o de profissionais qualificados, ajudando assim a fortalecer a educa\u00e7\u00e3o na regi\u00e3o.<\/p>\n<p>A abertura do curso STAPS na Universidade da Guiana representa, portanto, um passo significativo para o fortalecimento da educa\u00e7\u00e3o f\u00edsica e do esporte na regi\u00e3o, oferecendo oportunidades educacionais e profissionais aos alunos e contribuindo para o desenvolvimento local.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"A Universidade da Guiana acrescentar\u00e1 um curso totalmente novo \u00e0 sua gama de cursos a partir do in\u00edcio do ano acad\u00eamico...","protected":false},"author":1,"featured_media":8322,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":330,"footnotes":""},"categories":[224],"tags":[],"class_list":{"0":"post-8321","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-formation"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024 &#8212; Universit\u00e9 de Guyane<\/title>\n<meta name=\"description\" content=\"La licence STAPS rentr\u00e9e 2024 en Guyane : une formation polyvalente pour des carri\u00e8res imm\u00e9diates et des \u00e9tudes avanc\u00e9es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.univ-guyane.fr\/pt\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024 &#8212; Universit\u00e9 de Guyane\" \/>\n<meta property=\"og:description\" content=\"La licence STAPS rentr\u00e9e 2024 en Guyane : une formation polyvalente pour des carri\u00e8res imm\u00e9diates et des \u00e9tudes avanc\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.univ-guyane.fr\/pt\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Universit\u00e9 de Guyane\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univguyane\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T13:14:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T13:19:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/licence-staps-ug.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1013\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Loiti\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@univguyane\" \/>\n<meta name=\"twitter:site\" content=\"@univguyane\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Loiti\u00e8re\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/\"},\"author\":{\"name\":\"Erick Loiti\u00e8re\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\"},\"headline\":\"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024\",\"datePublished\":\"2024-01-26T13:14:24+00:00\",\"dateModified\":\"2024-06-17T13:19:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/\"},\"wordCount\":724,\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/licence-staps-ug.jpeg\",\"articleSection\":[\"\u2022 Formation\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/\",\"name\":\"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024 &#8212; Universit\u00e9 de Guyane\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/licence-staps-ug.jpeg\",\"datePublished\":\"2024-01-26T13:14:24+00:00\",\"dateModified\":\"2024-06-17T13:19:30+00:00\",\"description\":\"La licence STAPS rentr\u00e9e 2024 en Guyane : une formation polyvalente pour des carri\u00e8res imm\u00e9diates et des \u00e9tudes avanc\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/licence-staps-ug.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/licence-staps-ug.jpeg\",\"width\":1800,\"height\":1013,\"caption\":\"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2024\\\/01\\\/26\\\/ouverture-de-la-licence-staps-a-la-rentree-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"name\":\"Universit\u00e9 de Guyane\",\"description\":\"Au c\u0153ur de l&#039;amazonie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"alternateName\":\"UG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.univ-guyane.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\",\"name\":\"Universit\u00e9 de Guyane\",\"alternateName\":\"UG\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"width\":1024,\"height\":1024,\"caption\":\"Universit\u00e9 de Guyane\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univguyane\",\"https:\\\/\\\/x.com\\\/univguyane\",\"https:\\\/\\\/gf.linkedin.com\\\/school\\\/universite-de-guyane\\\/\",\"https:\\\/\\\/www.instagram.com\\\/univ_guyane\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\",\"name\":\"Erick Loiti\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"caption\":\"Erick Loiti\u00e8re\"},\"sameAs\":[\"http:\\\/\\\/www.univ-guyane.fr\"],\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/pt\\\/author\\\/eloitierdbz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024 &#8212; Universit\u00e9 de Guyane","description":"La licence STAPS rentr\u00e9e 2024 en Guyane : une formation polyvalente pour des carri\u00e8res imm\u00e9diates et des \u00e9tudes avanc\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.univ-guyane.fr\/pt\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/","og_locale":"pt_BR","og_type":"article","og_title":"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024 &#8212; Universit\u00e9 de Guyane","og_description":"La licence STAPS rentr\u00e9e 2024 en Guyane : une formation polyvalente pour des carri\u00e8res imm\u00e9diates et des \u00e9tudes avanc\u00e9es.","og_url":"https:\/\/www.univ-guyane.fr\/pt\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/","og_site_name":"Universit\u00e9 de Guyane","article_publisher":"https:\/\/www.facebook.com\/univguyane","article_published_time":"2024-01-26T13:14:24+00:00","article_modified_time":"2024-06-17T13:19:30+00:00","og_image":[{"width":1800,"height":1013,"url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/licence-staps-ug.jpeg","type":"image\/jpeg"}],"author":"Erick Loiti\u00e8re","twitter_card":"summary_large_image","twitter_creator":"@univguyane","twitter_site":"@univguyane","twitter_misc":{"Escrito por":"Erick Loiti\u00e8re","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/#article","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/"},"author":{"name":"Erick Loiti\u00e8re","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179"},"headline":"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024","datePublished":"2024-01-26T13:14:24+00:00","dateModified":"2024-06-17T13:19:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/"},"wordCount":724,"publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/licence-staps-ug.jpeg","articleSection":["\u2022 Formation"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/","url":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/","name":"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024 &#8212; Universit\u00e9 de Guyane","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/licence-staps-ug.jpeg","datePublished":"2024-01-26T13:14:24+00:00","dateModified":"2024-06-17T13:19:30+00:00","description":"La licence STAPS rentr\u00e9e 2024 en Guyane : une formation polyvalente pour des carri\u00e8res imm\u00e9diates et des \u00e9tudes avanc\u00e9es.","breadcrumb":{"@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/#primaryimage","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/licence-staps-ug.jpeg","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/licence-staps-ug.jpeg","width":1800,"height":1013,"caption":"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/www.univ-guyane.fr\/2024\/01\/26\/ouverture-de-la-licence-staps-a-la-rentree-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.univ-guyane.fr\/"},{"@type":"ListItem","position":2,"name":"Ouverture de la licence STAPS \u00e0 la rentr\u00e9e 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.univ-guyane.fr\/#website","url":"https:\/\/www.univ-guyane.fr\/","name":"Universidade da Guiana","description":"No cora\u00e7\u00e3o da Amaz\u00f4nia","publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"alternateName":"UG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.univ-guyane.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.univ-guyane.fr\/#organization","name":"Universidade da Guiana","alternateName":"UG","url":"https:\/\/www.univ-guyane.fr\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","width":1024,"height":1024,"caption":"Universit\u00e9 de Guyane"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univguyane","https:\/\/x.com\/univguyane","https:\/\/gf.linkedin.com\/school\/universite-de-guyane\/","https:\/\/www.instagram.com\/univ_guyane\/"]},{"@type":"Person","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179","name":"Erick Loiti\u00e8re","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","caption":"Erick Loiti\u00e8re"},"sameAs":["http:\/\/www.univ-guyane.fr"],"url":"https:\/\/www.univ-guyane.fr\/pt\/author\/eloitierdbz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/posts\/8321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/comments?post=8321"}],"version-history":[{"count":1,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/posts\/8321\/revisions"}],"predecessor-version":[{"id":8323,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/posts\/8321\/revisions\/8323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/media\/8322"}],"wp:attachment":[{"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/media?parent=8321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/categories?post=8321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/tags?post=8321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}