{"id":8638,"date":"2022-11-30T11:23:16","date_gmt":"2022-11-30T14:23:16","guid":{"rendered":"https:\/\/www.univ-guyane.fr\/?p=8638"},"modified":"2024-06-18T11:31:09","modified_gmt":"2024-06-18T14:31:09","slug":"lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes","status":"publish","type":"post","link":"https:\/\/www.univ-guyane.fr\/pt\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/","title":{"rendered":"Lan\u00e7amento da Confer\u00eancia de Reitores das Universidades do Escudo das Guianas"},"content":{"rendered":"<div id=\"fws_6a0503c11644c\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  chapo\" >\n\t<h2>Ecoando o <a href=\"https:\/\/web.archive.org\/web\/20231129174702\/https:\/\/www.univ-guyane.fr\/2022\/06\/mission-guyuniv2\/\">Miss\u00e3o GUYUNIV2<\/a>Ap\u00f3s sua miss\u00e3o explorat\u00f3ria ao Suriname e \u00e0 Guiana em junho passado, a Universidade da Guiana recebeu tr\u00eas delega\u00e7\u00f5es universit\u00e1rias de 14 a 16 de novembro. A Universidade do Suriname (ADEKUS), a Universidade da Guiana (UoG) e a Universidade Federal do Amap\u00e1 (UNIFAP) se reuniram na Universidade da Guiana Francesa para lan\u00e7ar oficialmente a Confer\u00eancia de Reitores de Universidades do Escudo das Guianas.<\/h2>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p><span class=\"nectar-dropcap\" >L' <\/span>A Universit\u00e9 de Guyane organizou o lan\u00e7amento da primeira Confer\u00eancia de Reitores de Universidades do Planalto da Guiana. Na ocasi\u00e3o, ela recebeu seus parceiros da macrorregi\u00e3o: a Universidade do Suriname (ADEKUS), a Universidade da Guiana e a Universidade Federal do Amap\u00e1 (UNIFAP). Esse evento marca um ponto de virada e o in\u00edcio de uma grande aventura para as quatro institui\u00e7\u00f5es de ensino superior.<\/p>\n<p>Durante os tr\u00eas dias, as quatro institui\u00e7\u00f5es discutiram os problemas que enfrentam juntas, tanto em termos de pesquisa quanto de treinamento. A quest\u00e3o de uma identidade acad\u00eamica e universit\u00e1ria para a macrorregi\u00e3o do Escudo das Guianas veio \u00e0 tona. Os desafios enfrentados por esses territ\u00f3rios e pa\u00edses, as quest\u00f5es de sa\u00fade p\u00fablica e a riqueza de sua biodiversidade s\u00e3o temas comuns.<\/p>\n<p>Por meio dessa reuni\u00e3o, a Universidade da Guiana Francesa espera estabelecer as bases para um cons\u00f3rcio de universidades do Escudo das Guianas, que deve se expandir, a fim de impulsionar iniciativas educacionais e cient\u00edficas entre as quatro universidades. A reuni\u00e3o tamb\u00e9m proporcionar\u00e1 uma oportunidade para lan\u00e7ar as bases de tr\u00eas projetos-chave: o Instituto Amaz\u00f4nico de Biodiversidade e Inova\u00e7\u00e3o Sustent\u00e1vel (AIBSI), a cria\u00e7\u00e3o de uma imprensa universit\u00e1ria para o Escudo das Guianas e a cria\u00e7\u00e3o de uma confer\u00eancia de doutorado no norte da Amaz\u00f4nia.<\/p>\n<h3><strong>Cria\u00e7\u00e3o de uma identidade universit\u00e1ria macrorregional<\/strong><\/h3>\n<p>Durante os tr\u00eas dias, foi organizada uma sess\u00e3o matinal para estabelecer as bases dos tr\u00eas principais projetos que ajudar\u00e3o a construir uma identidade acad\u00eamica e universit\u00e1ria macrorregional para o Planalto da Guiana.<\/p>\n<p>AIBSI (Instituto Amaz\u00f4nico de Biodiversidade e Inova\u00e7\u00e3o Sustent\u00e1vel): uma estrutura operacional para apoiar o surgimento de uma identidade acad\u00eamica e universit\u00e1ria macrorregional;<\/p>\n<p>Uma confer\u00eancia de doutorado da Amaz\u00f4nia do Norte como um f\u00f3rum para a constru\u00e7\u00e3o de uma identidade acad\u00eamica por meio de treinamento de alto n\u00edvel. A cria\u00e7\u00e3o de um programa de treinamento de doutorado amaz\u00f4nico poderia contribuir muito para fortalecer o surgimento no Escudo das Guianas de redes de especialistas e peritos na Amaz\u00f4nia, com foco em quest\u00f5es como o conhecimento da biodiversidade, o meio ambiente, o uso de tecnologias inovadoras, o conhecimento de nossas sociedades no Escudo das Guianas e quest\u00f5es de desenvolvimento.<\/p>\n<p>Uma imprensa universit\u00e1ria para o Planalto das Guianas: uma ferramenta para a constru\u00e7\u00e3o de uma identidade macrorregional. O objetivo \u00e9 elevar o perfil internacional das publica\u00e7\u00f5es cient\u00edficas e educacionais, bem como dos trabalhos populares das quatro institui\u00e7\u00f5es. Ao reunir as habilidades das quatro institui\u00e7\u00f5es, a ideia de uma imprensa universit\u00e1ria compartilhada poderia criar um espa\u00e7o real no qual seus cientistas e estudantes de doutorado poderiam publicar seus trabalhos.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Ap\u00f3s a miss\u00e3o explorat\u00f3ria do GUYUNIV2 ao Suriname e \u00e0 Guiana em junho...","protected":false},"author":1,"featured_media":8639,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":26,"footnotes":""},"categories":[170,229],"tags":[],"class_list":{"0":"post-8638","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-international","8":"category-universite-actualites"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes &#8212; Universit\u00e9 de Guyane<\/title>\n<meta name=\"description\" content=\"L&#039;Universit\u00e9 de Guyane accueille la premi\u00e8re Conf\u00e9rence des Recteurs d&#039;Universit\u00e9s du Plateau des Guyanes. Un moment cl\u00e9 pour les partenaires universitaires de la macro-r\u00e9gion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.univ-guyane.fr\/pt\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes &#8212; Universit\u00e9 de Guyane\" \/>\n<meta property=\"og:description\" content=\"L&#039;Universit\u00e9 de Guyane accueille la premi\u00e8re Conf\u00e9rence des Recteurs d&#039;Universit\u00e9s du Plateau des Guyanes. Un moment cl\u00e9 pour les partenaires universitaires de la macro-r\u00e9gion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.univ-guyane.fr\/pt\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/\" \/>\n<meta property=\"og:site_name\" content=\"Universit\u00e9 de Guyane\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univguyane\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-30T14:23:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-18T14:31:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1013\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Loiti\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@univguyane\" \/>\n<meta name=\"twitter:site\" content=\"@univguyane\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Loiti\u00e8re\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/\"},\"author\":{\"name\":\"Erick Loiti\u00e8re\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\"},\"headline\":\"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes\",\"datePublished\":\"2022-11-30T14:23:16+00:00\",\"dateModified\":\"2024-06-18T14:31:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/\"},\"wordCount\":761,\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg\",\"articleSection\":[\"\u2022 International\",\"\u2022 Universit\u00e9\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/\",\"name\":\"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes &#8212; Universit\u00e9 de Guyane\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg\",\"datePublished\":\"2022-11-30T14:23:16+00:00\",\"dateModified\":\"2024-06-18T14:31:09+00:00\",\"description\":\"L'Universit\u00e9 de Guyane accueille la premi\u00e8re Conf\u00e9rence des Recteurs d'Universit\u00e9s du Plateau des Guyanes. Un moment cl\u00e9 pour les partenaires universitaires de la macro-r\u00e9gion.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg\",\"width\":1800,\"height\":1013,\"caption\":\"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/2022\\\/11\\\/30\\\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"name\":\"Universit\u00e9 de Guyane\",\"description\":\"Au c\u0153ur de l&#039;amazonie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\"},\"alternateName\":\"UG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.univ-guyane.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#organization\",\"name\":\"Universit\u00e9 de Guyane\",\"alternateName\":\"UG\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"contentUrl\":\"https:\\\/\\\/www.univ-guyane.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/f.png\",\"width\":1024,\"height\":1024,\"caption\":\"Universit\u00e9 de Guyane\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univguyane\",\"https:\\\/\\\/x.com\\\/univguyane\",\"https:\\\/\\\/gf.linkedin.com\\\/school\\\/universite-de-guyane\\\/\",\"https:\\\/\\\/www.instagram.com\\\/univ_guyane\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.univ-guyane.fr\\\/#\\\/schema\\\/person\\\/86d946a28a8be51bb096ccfdf19db179\",\"name\":\"Erick Loiti\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g\",\"caption\":\"Erick Loiti\u00e8re\"},\"sameAs\":[\"http:\\\/\\\/www.univ-guyane.fr\"],\"url\":\"https:\\\/\\\/www.univ-guyane.fr\\\/pt\\\/author\\\/eloitierdbz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes &#8212; Universit\u00e9 de Guyane","description":"L'Universit\u00e9 de Guyane accueille la premi\u00e8re Conf\u00e9rence des Recteurs d'Universit\u00e9s du Plateau des Guyanes. Un moment cl\u00e9 pour les partenaires universitaires de la macro-r\u00e9gion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.univ-guyane.fr\/pt\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/","og_locale":"pt_BR","og_type":"article","og_title":"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes &#8212; Universit\u00e9 de Guyane","og_description":"L'Universit\u00e9 de Guyane accueille la premi\u00e8re Conf\u00e9rence des Recteurs d'Universit\u00e9s du Plateau des Guyanes. Un moment cl\u00e9 pour les partenaires universitaires de la macro-r\u00e9gion.","og_url":"https:\/\/www.univ-guyane.fr\/pt\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/","og_site_name":"Universit\u00e9 de Guyane","article_publisher":"https:\/\/www.facebook.com\/univguyane","article_published_time":"2022-11-30T14:23:16+00:00","article_modified_time":"2024-06-18T14:31:09+00:00","og_image":[{"width":1800,"height":1013,"url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg","type":"image\/jpeg"}],"author":"Erick Loiti\u00e8re","twitter_card":"summary_large_image","twitter_creator":"@univguyane","twitter_site":"@univguyane","twitter_misc":{"Escrito por":"Erick Loiti\u00e8re","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/#article","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/"},"author":{"name":"Erick Loiti\u00e8re","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179"},"headline":"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes","datePublished":"2022-11-30T14:23:16+00:00","dateModified":"2024-06-18T14:31:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/"},"wordCount":761,"publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg","articleSection":["\u2022 International","\u2022 Universit\u00e9"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/","url":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/","name":"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes &#8212; Universit\u00e9 de Guyane","isPartOf":{"@id":"https:\/\/www.univ-guyane.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/#primaryimage"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg","datePublished":"2022-11-30T14:23:16+00:00","dateModified":"2024-06-18T14:31:09+00:00","description":"L'Universit\u00e9 de Guyane accueille la premi\u00e8re Conf\u00e9rence des Recteurs d'Universit\u00e9s du Plateau des Guyanes. Un moment cl\u00e9 pour les partenaires universitaires de la macro-r\u00e9gion.","breadcrumb":{"@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/#primaryimage","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/conference-des-recteurs-du-plateau-des-guyanes-2022.jpeg","width":1800,"height":1013,"caption":"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.univ-guyane.fr\/2022\/11\/30\/lancement-de-la-conference-des-recteurs-duniversites-du-plateau-des-guyanes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.univ-guyane.fr\/"},{"@type":"ListItem","position":2,"name":"Lancement de la Conf\u00e9rence des Recteurs d\u2019Universit\u00e9s du Plateau des Guyanes"}]},{"@type":"WebSite","@id":"https:\/\/www.univ-guyane.fr\/#website","url":"https:\/\/www.univ-guyane.fr\/","name":"Universidade da Guiana","description":"No cora\u00e7\u00e3o da Amaz\u00f4nia","publisher":{"@id":"https:\/\/www.univ-guyane.fr\/#organization"},"alternateName":"UG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.univ-guyane.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.univ-guyane.fr\/#organization","name":"Universidade da Guiana","alternateName":"UG","url":"https:\/\/www.univ-guyane.fr\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","contentUrl":"https:\/\/www.univ-guyane.fr\/wp-content\/uploads\/2024\/05\/f.png","width":1024,"height":1024,"caption":"Universit\u00e9 de Guyane"},"image":{"@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univguyane","https:\/\/x.com\/univguyane","https:\/\/gf.linkedin.com\/school\/universite-de-guyane\/","https:\/\/www.instagram.com\/univ_guyane\/"]},{"@type":"Person","@id":"https:\/\/www.univ-guyane.fr\/#\/schema\/person\/86d946a28a8be51bb096ccfdf19db179","name":"Erick Loiti\u00e8re","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0584f332103fbeaf37e52c73b15dca3c547fd9300deb05764e9ad8714839d072?s=96&d=robohash&r=g","caption":"Erick Loiti\u00e8re"},"sameAs":["http:\/\/www.univ-guyane.fr"],"url":"https:\/\/www.univ-guyane.fr\/pt\/author\/eloitierdbz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/posts\/8638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/comments?post=8638"}],"version-history":[{"count":1,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/posts\/8638\/revisions"}],"predecessor-version":[{"id":8640,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/posts\/8638\/revisions\/8640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/media\/8639"}],"wp:attachment":[{"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/media?parent=8638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/categories?post=8638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-guyane.fr\/pt\/wp-json\/wp\/v2\/tags?post=8638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}